{"id":9590,"date":"2024-11-19T21:44:20","date_gmt":"2024-11-20T03:44:20","guid":{"rendered":"https:\/\/nbm.com.mx\/?p=9590"},"modified":"2024-11-19T21:44:26","modified_gmt":"2024-11-20T03:44:26","slug":"mexico-ya-tiene-representantes-para-el-mundial-fisu-3x3","status":"publish","type":"post","link":"https:\/\/nbm.com.mx\/index.php\/2024\/11\/19\/mexico-ya-tiene-representantes-para-el-mundial-fisu-3x3\/","title":{"rendered":"M\u00e9xico ya tiene representantes para el Mundial FISU 3&#215;3"},"content":{"rendered":"\n<p>Las escuadras del Tec de Monterrey y el campus Toluca, participar\u00e1n en la <strong>FISU University World Cup 3&#215;3<\/strong> que se llevar\u00e1 a cabo en Xiamen, <strong>China<\/strong> del 22 al 24 de noviembre.<\/p>\n\n\n\n<p>Representando a las universidades mexicanas tenemos a la plantilla del Tec Toluca, integrada por <strong>Ana Karen S\u00e1nchez<\/strong>,<strong> Paola Soto<\/strong>,<strong> Mariana Lira<\/strong> y <strong>Elisa Rodr\u00edguez<\/strong>, dirigidas por el entrenador Diego Vallejo.<\/p>\n\n\n\n<p>Por otro lado, tenemos a la escuadra hermana, Tec de Monterrey, quienes buscan colgarse el oro por segunda vez consecutiva, logr\u00e1ndolo la primera el a\u00f1o pasado en Doha, Qatar. Dentro de las jugadoras que representar\u00e1n a la escuadra regiomontana est\u00e1n <strong>Karina Esquer<\/strong>, <strong>Anisa Jeffries<\/strong>, <strong>Irais Aguilera<\/strong> y <strong>Deyna Gonz\u00e1lez<\/strong>.<\/p>\n\n\n\n<script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-2648532975888472\" crossorigin=\"anonymous\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block; text-align:center;\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-2648532975888472\" data-ad-slot=\"1648043454\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/nbm.com.mx\/index.php\/2024\/10\/30\/quien-sera-el-jugador-mas-valioso-de-la-liga-abe-varonil\/\" target=\"_blank\" rel=\"noreferrer noopener\">Te puede interesar: \u00bfQui\u00e9n ser\u00e1 el Jugador M\u00e1s Valioso de la Liga ABE Varonil?<\/a><\/h4>\n\n\n\n<p>El FISU University World Cup, es un evento anual, el cual junta a diversas universidades del mundo a competir entre ellas, no solamente de basquetbol, sino de diferentes deportes como el futbol, volleyball o deportes de invierno. En el caso de M\u00e9xico, habr\u00e1 2 representantes, y una escuadra de esas dos, es el rival a vencer, pues el a\u00f1o pasado en Qatar, las Borregas del Tec Monterrey, fueron las que se llevaron el campeonato y este a\u00f1o buscan repetir la haza\u00f1a.<\/p>\n\n\n\n<p>El evento femenil dar\u00e1 inicio el pr\u00f3ximo 22 de noviembre en Xiamen, China, y tendr\u00e1 a las siguientes universidades participando en el evento:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tsinghua University (China)<\/li>\n\n\n\n<li>Uganda Christian University Wildcats (Uganda)<\/li>\n\n\n\n<li>Universitat de Val\u00e8ncia (Espa\u00f1a)<\/li>\n\n\n\n<li>ITESM campus Toluca (M\u00e9xico)<\/li>\n\n\n\n<li>ITESM Monterrey (M\u00e9xico)<\/li>\n\n\n\n<li>Yunnan Normal University (China)<\/li>\n\n\n\n<li>Carleton University (Canad\u00e1)<\/li>\n\n\n\n<li>University of Sydney (Australia)<\/li>\n\n\n\n<li>R\u012bgas Stradi\u0146a universit\u0101t\u0113 (Letonia)<\/li>\n\n\n\n<li>National Taiwan Normal University (Taiw\u00e1n)<\/li>\n\n\n\n<li>Szechenyi Istvan University (Hungr\u00eda)<\/li>\n\n\n\n<li>United States International University-Africa (Kenya)<\/li>\n<\/ul>\n\n\n\n<p>Los enfrentamientos se determinar\u00e1n una vez todos los equipos se encuentren en la provincia de Fujian y ser\u00e1n transmitidos a trav\u00e9s de las redes sociales de la Federaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Borregas del Tec de Monterrey y Tec Toluca representar\u00e1n al basquetbol femenil mexicano en el Mundial 3&#215;3 que se disputar\u00e1 en Xiamen, China.<\/p>\n","protected":false},"author":7,"featured_media":9591,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[126],"tags":[1721,1289,1907,630,1372,1375,1906,1290,1723,1121,865],"class_list":["post-9590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-anisa-jeffries","tag-deyna-gonzalez","tag-elisa-rodriguez-2","tag-fisu","tag-fisu-3x3","tag-irais-aguilera","tag-karen-sanchez","tag-karina-esquer","tag-mariana-lira","tag-tec-de-monterrey","tag-tec-de-monterrey-toluca"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/nbm.com.mx\/wp-content\/uploads\/2024\/11\/Tec-de-Monterrey.jpg?fit=1200%2C675&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/9590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=9590"}],"version-history":[{"count":1,"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/9590\/revisions"}],"predecessor-version":[{"id":9592,"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/9590\/revisions\/9592"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/media\/9591"}],"wp:attachment":[{"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=9590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=9590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=9590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}