{"id":1869,"date":"2021-08-13T00:30:18","date_gmt":"2021-08-13T05:30:18","guid":{"rendered":"https:\/\/nbm.com.mx\/?p=1869"},"modified":"2021-08-13T00:30:24","modified_gmt":"2021-08-13T05:30:24","slug":"mexico-ya-conoce-rivales-en-el-fiba-u16-americas-womens","status":"publish","type":"post","link":"https:\/\/nbm.com.mx\/index.php\/2021\/08\/13\/mexico-ya-conoce-rivales-en-el-fiba-u16-americas-womens\/","title":{"rendered":"M\u00e9xico ya conoce rivales en el FIBA U16 Americas Women\u00b4s"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">El FIBA U16 Americas Women\u00b4s Championship est\u00e1 a nada de comenzar en el \u201cDomo de la Feria\u201d en Le\u00f3n, Guanajuato y la selecci\u00f3n femenina se ubica en el Grupo B junto a Argentina, Chile y Estados Unidos; por lo que del 23 al 25 de agosto, las nacionales deber\u00e1n sortear la fase de grupos del siguiente modo:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/i0.wp.com\/nbm.com.mx\/wp-content\/uploads\/2021\/08\/E8eyUEXXoAIlkT0.jpeg?resize=1000%2C1000&#038;ssl=1\" alt=\"\" class=\"wp-image-1870\" srcset=\"https:\/\/i0.wp.com\/nbm.com.mx\/wp-content\/uploads\/2021\/08\/E8eyUEXXoAIlkT0.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/nbm.com.mx\/wp-content\/uploads\/2021\/08\/E8eyUEXXoAIlkT0.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/nbm.com.mx\/wp-content\/uploads\/2021\/08\/E8eyUEXXoAIlkT0.jpeg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/nbm.com.mx\/wp-content\/uploads\/2021\/08\/E8eyUEXXoAIlkT0.jpeg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/nbm.com.mx\/wp-content\/uploads\/2021\/08\/E8eyUEXXoAIlkT0.jpeg?resize=80%2C80&amp;ssl=1 80w, https:\/\/i0.wp.com\/nbm.com.mx\/wp-content\/uploads\/2021\/08\/E8eyUEXXoAIlkT0.jpeg?resize=128%2C128&amp;ssl=1 128w, https:\/\/i0.wp.com\/nbm.com.mx\/wp-content\/uploads\/2021\/08\/E8eyUEXXoAIlkT0.jpeg?resize=32%2C32&amp;ssl=1 32w, https:\/\/i0.wp.com\/nbm.com.mx\/wp-content\/uploads\/2021\/08\/E8eyUEXXoAIlkT0.jpeg?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption>Foto: Cortes\u00eda ADEMEBA<\/figcaption><\/figure>\n\n\n\n<p><strong>23 de agosto &#8211; M\u00e9xico vs Argentina a las 20:30 horas<\/strong><\/p>\n\n\n\n<p><strong>24 de agosto &#8211; M\u00e9xico vs Estados Unidos a las 20:30 horas<\/strong><\/p>\n\n\n\n<p><strong>25 de agosto &#8211; Chile vs M\u00e9xico a las 20:30 horas<\/strong><\/p>\n\n\n\n<p>26 de agosto &#8211; D\u00eda de descanso.&nbsp;<\/p>\n\n\n\n<p>El grupo A est\u00e1 conformado por Puerto Rico, Canad\u00e1, Brasil y Costa Rica.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El 27 de agosto se disputar\u00e1n los cuartos de final, calificando las 8 naciones participantes, pero s\u00f3lo 4 de ellas podr\u00e1n obtener un boleto al Mundial U17 de 2022 en Debrecen, Hungr\u00eda. Los enfrentamientos son:<\/p>\n\n\n\n<p>1\u00b0A \u2013 4\u00b0B<\/p>\n\n\n\n<p>2\u00b0A \u2013 3\u00b0B<\/p>\n\n\n\n<p>2\u00b0B \u2013 3\u00b0A<\/p>\n\n\n\n<p>1\u00b0B \u2013 4\u00b0A<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El 28 de agosto se jugar\u00edan la reclasificaci\u00f3n del 5\u00b0 a 8\u00b0 entre las selecciones sin boleto, para que las semis tengan lugar de manera inmediata.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El d\u00eda del cierre, se disputar\u00e1n la clasificaci\u00f3n de 7\u00b0 y 5\u00b0, para despu\u00e9s darse la pelea por el bronce y concluir con la pelea por el oro.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Todos los partidos se transmitir\u00e1n en vivo a trav\u00e9s del canal de Youtube de FIBA y con retransmisi\u00f3n por AYM Sports y redes de Ademeba; el torneo se jugar\u00e1 bajo el formato de \u201cburbuja\u201d y se continuar\u00e1n siguiendo los protocolos de FIBA COVID para garantizar la seguridad de los jugadores y de todos los participantes, de acuerdo al portal de noticias FIBA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El FIBA U16 Americas Women\u00b4s Championship est\u00e1 a nada de comenzar en el \u201cDomo de la Feria\u201d en Le\u00f3n, Guanajuato y la selecci\u00f3n femenina se ubica en el Grupo B junto a Argentina, Chile y Estados Unidos<\/p>\n","protected":false},"author":6,"featured_media":1870,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[126],"tags":[137,232,166,554,139,496],"class_list":["post-1869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-femenil","tag-fiba","tag-fiba-americas","tag-guanajuato","tag-seleccion-nacional","tag-u16"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/nbm.com.mx\/wp-content\/uploads\/2021\/08\/E8eyUEXXoAIlkT0.jpeg?fit=1080%2C1080&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1869"}],"version-history":[{"count":1,"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1869\/revisions"}],"predecessor-version":[{"id":1871,"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/1869\/revisions\/1871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/media\/1870"}],"wp:attachment":[{"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nbm.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}